{"id":97,"date":"2026-06-20T12:49:38","date_gmt":"2026-06-20T12:49:38","guid":{"rendered":"https:\/\/amkdiaspora.com\/donativos\/"},"modified":"2026-07-26T15:14:42","modified_gmt":"2026-07-26T15:14:42","slug":"donativos","status":"publish","type":"page","link":"https:\/\/amkdiaspora.com\/en\/donativos\/","title":{"rendered":"Apoios"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"97\" class=\"elementor elementor-97\">\n\t\t\t\t<div data-aos=\"fade-up\" class=\"hostinger-elementor-aos elementor-element elementor-element-4416749 e-grid hostinger-ai-about-us-3 e-con-boxed e-con e-parent\" data-id=\"4416749\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ac8816c ai-image hostinger-index-4 elementor-widget elementor-widget-image\" data-id=\"ac8816c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/amkdiaspora.com\/wp-content\/uploads\/2026\/07\/apoios.png\" class=\"attachment-full size-full wp-image-2039\" alt=\"\" srcset=\"https:\/\/amkdiaspora.com\/wp-content\/uploads\/2026\/07\/apoios.png 300w, https:\/\/amkdiaspora.com\/wp-content\/uploads\/2026\/07\/apoios-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div data-aos=\"fade-up\" class=\"hostinger-elementor-aos elementor-element elementor-element-ac68c9f e-con-full e-flex e-con e-child\" data-id=\"ac68c9f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2516ff0 hostinger-ai-title elementor-widget elementor-widget-heading\" data-id=\"2516ff0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Apoie a nossa miss\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb2189c elementor-widget__width-initial hostinger-ai-description elementor-widget elementor-widget-text-editor\" data-id=\"bb2189c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Cada contribui\u00e7\u00e3o, por mais pequena que seja, ajuda a manter os nossos eventos abertos, os nossos projetos vivos e a nossa porta sempre acolhedora.<\/p><h4 style=\"text-align: left;\" data-en=\"Where your support goes\" data-pt=\"Para onde vai o seu apoio\">Para onde vai o seu apoio<\/h4><ul><li style=\"text-align: left;\">Aluguer de espa\u00e7os para encontros, forma\u00e7\u00f5es e eventos abertos \u00e0 comunidade.<\/li><li style=\"text-align: left;\">Material e log\u00edstica para oficinas culturais e projetos educativos.<\/li><li style=\"text-align: left;\">Fundo de apoio a membros em situa\u00e7\u00e3o de necessidade.<\/li><li style=\"text-align: left;\">Comunica\u00e7\u00e3o, manuten\u00e7\u00e3o da associa\u00e7\u00e3o e despesas administrativas.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b83388 elementor-widget elementor-widget-shortcode\" data-id=\"3b83388\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class='root-data-givewp-embed' data-form-locale='en_GB' data-form-url='https:\/\/amkdiaspora.com\/?post_type=give_forms&amp;p=2119' data-form-view-url='https:\/\/amkdiaspora.com\/en\/?givewp-route=donation-form-view&amp;form-id=2119' data-src='https:\/\/amkdiaspora.com\/en\/?givewp-route=donation-form-view&amp;form-id=2119' data-givewp-embed-id='give-form-shortcode-1' data-form-format='' data-open-form-button='Donate now' style='--givewp-primary-color: #dab94f; --givewp-secondary-color: #181818;'><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div>","protected":false},"excerpt":{"rendered":"<p>Apoie a nossa miss\u00e3o Cada contribui\u00e7\u00e3o, por mais pequena que seja, ajuda a manter os nossos eventos abertos, os nossos projetos vivos e a nossa porta sempre acolhedora. Para onde vai o seu apoio Aluguer de espa\u00e7os para encontros, forma\u00e7\u00f5es e eventos abertos \u00e0 comunidade. Material e log\u00edstica para oficinas culturais e projetos educativos. Fundo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"give_campaign_id":0,"_angie_page":false,"_monsterinsights_skip_tracking":false,"postBodyCss":"","postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"footnotes":""},"class_list":["post-97","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Apoie a nossa miss\u00e3o Cada contribui\u00e7\u00e3o, por mais pequena que seja, ajuda a manter os nossos eventos abertos, os nossos projetos vivos e a nossa porta sempre acolhedora.Para onde vai o seu apoioAluguer de espa\u00e7os para encontros, forma\u00e7\u00f5es e eventos abertos \u00e0 comunidade.Material e log\u00edstica para oficinas culturais e projetos educativos.Fundo de apoio a membros Contribua para a amkd e ajude-nos a continuar a nossa miss\u00e3o desde 2021 com doa\u00e7\u00f5es simples e seguras.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/amkdiaspora.com\/en\/donativos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"AMKD - Mwana Katchokwe na Di\u00e1sp\u00f3ora\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Doa\u00e7\u00f5es seguras para apoiar a amkd\" \/>\n\t\t<meta property=\"og:description\" content=\"Apoie a nossa miss\u00e3o Cada contribui\u00e7\u00e3o, por mais pequena que seja, ajuda a manter os nossos eventos abertos, os nossos projetos vivos e a nossa porta sempre acolhedora.Para onde vai o seu apoioAluguer de espa\u00e7os para encontros, forma\u00e7\u00f5es e eventos abertos \u00e0 comunidade.Material e log\u00edstica para oficinas culturais e projetos educativos.Fundo de apoio a membros Contribua para a amkd e ajude-nos a continuar a nossa miss\u00e3o desde 2021 com doa\u00e7\u00f5es simples e seguras.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/amkdiaspora.com\/en\/donativos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-20T12:49:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-26T15:14:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Doa\u00e7\u00f5es seguras para apoiar a amkd\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Apoie a nossa miss\u00e3o Cada contribui\u00e7\u00e3o, por mais pequena que seja, ajuda a manter os nossos eventos abertos, os nossos projetos vivos e a nossa porta sempre acolhedora.Para onde vai o seu apoioAluguer de espa\u00e7os para encontros, forma\u00e7\u00f5es e eventos abertos \u00e0 comunidade.Material e log\u00edstica para oficinas culturais e projetos educativos.Fundo de apoio a membros Contribua para a amkd e ajude-nos a continuar a nossa miss\u00e3o desde 2021 com doa\u00e7\u00f5es simples e seguras.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/donativos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amkdiaspora.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amkdiaspora.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/donativos\\\/#listItem\",\"name\":\"Apoios\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/donativos\\\/#listItem\",\"position\":2,\"name\":\"Apoios\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amkdiaspora.com\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/#organization\",\"name\":\"AMKD\",\"description\":\"Mwana Katchokwe na Di\\u00e1sp\\u00f3ora\",\"url\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/donativos\\\/#webpage\",\"url\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/donativos\\\/\",\"name\":\"Doa\\u00e7\\u00f5es seguras para apoiar a amkd\",\"description\":\"Apoie a nossa miss\\u00e3o Cada contribui\\u00e7\\u00e3o, por mais pequena que seja, ajuda a manter os nossos eventos abertos, os nossos projetos vivos e a nossa porta sempre acolhedora.Para onde vai o seu apoioAluguer de espa\\u00e7os para encontros, forma\\u00e7\\u00f5es e eventos abertos \\u00e0 comunidade.Material e log\\u00edstica para oficinas culturais e projetos educativos.Fundo de apoio a membros Contribua para a amkd e ajude-nos a continuar a nossa miss\\u00e3o desde 2021 com doa\\u00e7\\u00f5es simples e seguras.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/donativos\\\/#breadcrumblist\"},\"datePublished\":\"2026-06-20T12:49:38+00:00\",\"dateModified\":\"2026-07-26T15:14:42+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/\",\"name\":\"AMKD\",\"description\":\"Mwana Katchokwe na Di\\u00e1sp\\u00f3ora\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/amkdiaspora.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Doa\u00e7\u00f5es seguras para apoiar a amkd","description":"Apoie a nossa miss\u00e3o Cada contribui\u00e7\u00e3o, por mais pequena que seja, ajuda a manter os nossos eventos abertos, os nossos projetos vivos e a nossa porta sempre acolhedora.Para onde vai o seu apoioAluguer de espa\u00e7os para encontros, forma\u00e7\u00f5es e eventos abertos \u00e0 comunidade.Material e log\u00edstica para oficinas culturais e projetos educativos.Fundo de apoio a membros Contribua para a amkd e ajude-nos a continuar a nossa miss\u00e3o desde 2021 com doa\u00e7\u00f5es simples e seguras.","canonical_url":"https:\/\/amkdiaspora.com\/en\/donativos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/amkdiaspora.com\/en\/donativos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/amkdiaspora.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/amkdiaspora.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/amkdiaspora.com\/en\/donativos\/#listItem","name":"Apoios"}},{"@type":"ListItem","@id":"https:\/\/amkdiaspora.com\/en\/donativos\/#listItem","position":2,"name":"Apoios","previousItem":{"@type":"ListItem","@id":"https:\/\/amkdiaspora.com\/en#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/amkdiaspora.com\/en\/#organization","name":"AMKD","description":"Mwana Katchokwe na Di\u00e1sp\u00f3ora","url":"https:\/\/amkdiaspora.com\/en\/"},{"@type":"WebPage","@id":"https:\/\/amkdiaspora.com\/en\/donativos\/#webpage","url":"https:\/\/amkdiaspora.com\/en\/donativos\/","name":"Doa\u00e7\u00f5es seguras para apoiar a amkd","description":"Apoie a nossa miss\u00e3o Cada contribui\u00e7\u00e3o, por mais pequena que seja, ajuda a manter os nossos eventos abertos, os nossos projetos vivos e a nossa porta sempre acolhedora.Para onde vai o seu apoioAluguer de espa\u00e7os para encontros, forma\u00e7\u00f5es e eventos abertos \u00e0 comunidade.Material e log\u00edstica para oficinas culturais e projetos educativos.Fundo de apoio a membros Contribua para a amkd e ajude-nos a continuar a nossa miss\u00e3o desde 2021 com doa\u00e7\u00f5es simples e seguras.","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/amkdiaspora.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/amkdiaspora.com\/en\/donativos\/#breadcrumblist"},"datePublished":"2026-06-20T12:49:38+00:00","dateModified":"2026-07-26T15:14:42+00:00"},{"@type":"WebSite","@id":"https:\/\/amkdiaspora.com\/en\/#website","url":"https:\/\/amkdiaspora.com\/en\/","name":"AMKD","description":"Mwana Katchokwe na Di\u00e1sp\u00f3ora","inLanguage":"en-GB","publisher":{"@id":"https:\/\/amkdiaspora.com\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"AMKD - Mwana Katchokwe na Di\u00e1sp\u00f3ora","og:type":"article","og:title":"Doa\u00e7\u00f5es seguras para apoiar a amkd","og:description":"Apoie a nossa miss\u00e3o Cada contribui\u00e7\u00e3o, por mais pequena que seja, ajuda a manter os nossos eventos abertos, os nossos projetos vivos e a nossa porta sempre acolhedora.Para onde vai o seu apoioAluguer de espa\u00e7os para encontros, forma\u00e7\u00f5es e eventos abertos \u00e0 comunidade.Material e log\u00edstica para oficinas culturais e projetos educativos.Fundo de apoio a membros Contribua para a amkd e ajude-nos a continuar a nossa miss\u00e3o desde 2021 com doa\u00e7\u00f5es simples e seguras.","og:url":"https:\/\/amkdiaspora.com\/en\/donativos\/","article:published_time":"2026-06-20T12:49:38+00:00","article:modified_time":"2026-07-26T15:14:42+00:00","twitter:card":"summary_large_image","twitter:title":"Doa\u00e7\u00f5es seguras para apoiar a amkd","twitter:description":"Apoie a nossa miss\u00e3o Cada contribui\u00e7\u00e3o, por mais pequena que seja, ajuda a manter os nossos eventos abertos, os nossos projetos vivos e a nossa porta sempre acolhedora.Para onde vai o seu apoioAluguer de espa\u00e7os para encontros, forma\u00e7\u00f5es e eventos abertos \u00e0 comunidade.Material e log\u00edstica para oficinas culturais e projetos educativos.Fundo de apoio a membros Contribua para a amkd e ajude-nos a continuar a nossa miss\u00e3o desde 2021 com doa\u00e7\u00f5es simples e seguras."},"aioseo_meta_data":{"post_id":"97","title":"Doa\u00e7\u00f5es seguras para apoiar a amkd","description":"#post_excerpt Contribua para a amkd e ajude-nos a continuar a nossa miss\u00e3o desde 2021 com doa\u00e7\u00f5es simples e seguras.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-06-20 12:49:49","updated":"2026-07-26 16:03:36"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/amkdiaspora.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tApoios\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/amkdiaspora.com\/en"},{"label":"Apoios","link":"https:\/\/amkdiaspora.com\/en\/donativos\/"}],"campaignId":"","_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/amkdiaspora.com\/en\/wp-json\/wp\/v2\/pages\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amkdiaspora.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amkdiaspora.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amkdiaspora.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amkdiaspora.com\/en\/wp-json\/wp\/v2\/comments?post=97"}],"version-history":[{"count":61,"href":"https:\/\/amkdiaspora.com\/en\/wp-json\/wp\/v2\/pages\/97\/revisions"}],"predecessor-version":[{"id":2129,"href":"https:\/\/amkdiaspora.com\/en\/wp-json\/wp\/v2\/pages\/97\/revisions\/2129"}],"wp:attachment":[{"href":"https:\/\/amkdiaspora.com\/en\/wp-json\/wp\/v2\/media?parent=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}